{"id":100680,"date":"2026-07-15T14:54:57","date_gmt":"2026-07-15T14:54:57","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/doppelmayr-construira-simultaneamente-la-linea-5-del-cablebus-en-cdmx-y-el-sistema-de-transporte-por-cable-en-puebla\/"},"modified":"2026-07-15T20:54:58","modified_gmt":"2026-07-15T20:54:58","slug":"doppelmayr-construira-simultaneamente-la-linea-5-del-cablebus-en-cdmx-y-el-sistema-de-transporte-por-cable-en-puebla","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/doppelmayr-construira-simultaneamente-la-linea-5-del-cablebus-en-cdmx-y-el-sistema-de-transporte-por-cable-en-puebla\/","title":{"rendered":"Doppelmayr construir\u00e1 simult\u00e1neamente la L\u00ednea 5 del Cableb\u00fas en CDMX y el sistema de transporte por cable en Puebla"},"content":{"rendered":"<p>La empresa austriaca Doppelmayr, l\u00edder mundial en la construcci\u00f3n de sistemas de transporte por cable, desarrolla de manera paralela dos proyectos emblem\u00e1ticos en M\u00e9xico: la L\u00ednea 5 del Cableb\u00fas de la Ciudad de M\u00e9xico y el Sistema de Transporte por Cable de Puebla. Ambas obras avanzan pr\u00e1cticamente al mismo tiempo y tienen previsto concluir durante 2029, con inicio de operaciones comerciales a finales de ese a\u00f1o o a principios de 2030.  <\/p>\n<p>Mientras que en la capital del pa\u00eds el Gobierno de la Ciudad de M\u00e9xico dio esta semana el banderazo de inicio para la construcci\u00f3n de la L\u00ednea 5, en Puebla el proyecto se encuentra en la fase de desarrollo ejecutivo, liberaci\u00f3n del derecho de v\u00eda, estudios especializados y primeras etapas de ejecuci\u00f3n. Este sistema poblano conectar\u00e1 diversos puntos de la zona metropolitana a trav\u00e9s de cuatro l\u00edneas de transporte a\u00e9reo.  <\/p>\n<p>La L\u00ednea 5 del Cableb\u00fas capitalino tendr\u00e1 una extensi\u00f3n de 15.4 kil\u00f3metros, con 12 estaciones, 114 torres y 462 cabinas con capacidad para diez pasajeros cada una. Se estima que beneficiar\u00e1 a m\u00e1s de 137 mil habitantes de las alcald\u00edas \u00c1lvaro Obreg\u00f3n y Magdalena Contreras, con una reducci\u00f3n de hasta 50 por ciento en los tiempos de traslado.  <\/p>\n<p>Por su parte, el proyecto poblano contempla una red de 14.77 kil\u00f3metros, integrada por cuatro l\u00edneas y nueve estaciones, con 152 cabinas para diez pasajeros cada una. Su capacidad inicial permitir\u00e1 movilizar alrededor de 38 mil usuarios diarios, con un dise\u00f1o que puede alcanzar hasta 90 mil pasajeros conforme aumente la demanda.  <\/p>\n<p>El Sistema de Transporte por Cable en Puebla representa una inversi\u00f3n superior a 6 mil 752 millones de pesos con IVA, recursos que se ejercer\u00e1n de manera multianual entre 2025 y 2029. El componente electromec\u00e1nico, que incluye cabinas, motores, cables, torres, sistemas inteligentes de operaci\u00f3n y recaudo electr\u00f3nico, absorber\u00e1 m\u00e1s de 4 mil 216 millones de pesos, es decir, el 62.4 por ciento del presupuesto total.  <\/p>\n<p>Adem\u00e1s, se destinar\u00e1n 212 millones de pesos para mitigaci\u00f3n ambiental, adquisici\u00f3n de predios, liberaci\u00f3n del derecho de v\u00eda y reubicaci\u00f3n de infraestructura de organismos como CFE, SOAPAP, Telmex, Pemex y empresas distribuidoras de gas.  <\/p>\n<p>Aunque la L\u00ednea 5 del Cableb\u00fas capitalino inici\u00f3 formalmente su construcci\u00f3n esta semana, el proyecto poblano comenz\u00f3 su ejecuci\u00f3n desde diciembre de 2025. Ambos comparten un calendario similar para los pr\u00f3ximos cuatro a\u00f1os: en Puebla, la obra concluir\u00e1 el 1 de noviembre de 2029, con pruebas y certificaci\u00f3n internacional para iniciar operaciones en enero de 2030. En la Ciudad de M\u00e9xico, la L\u00ednea 5 estar\u00eda terminada alrededor de mayo de 2029, unos meses antes que el proyecto poblano.  <\/p>\n<p>M\u00e1s all\u00e1 de las diferencias en dimensiones y contexto, ambos sistemas buscan reducir los tiempos de traslado en zonas con alta congesti\u00f3n vehicular. En Puebla, los estudios de movilidad estiman que el recorrido completo entre Mayorazgo y el Cerro de Amalucan podr\u00e1 realizarse en 43.76 minutos, lo que representa una reducci\u00f3n de hasta 46 por ciento respecto a los tiempos actuales en horas pico.  <\/p>\n<p>El sistema poblano tambi\u00e9n contempla la integraci\u00f3n con las l\u00edneas de RUTA, rutas convencionales y una futura red estatal de bicicletas p\u00fablicas para facilitar la movilidad de primera y \u00faltima milla. En la Ciudad de M\u00e9xico, la L\u00ednea 5 enlazar\u00e1 con las l\u00edneas 7 y 12 del Metro, fortaleciendo la conectividad en el poniente de la capital.  <\/p>\n<p>Estos proyectos, que mantienen a Doppelmayr como actor principal en la construcci\u00f3n de sistemas de transporte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa austriaca Doppelmayr, l\u00edder mundial en la construcci\u00f3n de sistemas de transporte por cable, desarrolla de manera paralela dos proyectos emblem\u00e1ticos en M\u00e9xico: la L\u00ednea 5 del Cableb\u00fas de la Ciudad de M\u00e9xico y el Sistema de Transporte por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-100680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100680"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100680\/revisions"}],"predecessor-version":[{"id":100681,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100680\/revisions\/100681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100679"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}