{"id":100659,"date":"2026-07-15T13:22:49","date_gmt":"2026-07-15T13:22:49","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/tec-de-monterrey-invito-al-presunto-tirador-de-la-atlixcayotl-a-su-consejo-consultivo-antes-de-su-detencion\/"},"modified":"2026-07-15T19:22:52","modified_gmt":"2026-07-15T19:22:52","slug":"tec-de-monterrey-invito-al-presunto-tirador-de-la-atlixcayotl-a-su-consejo-consultivo-antes-de-su-detencion","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/tec-de-monterrey-invito-al-presunto-tirador-de-la-atlixcayotl-a-su-consejo-consultivo-antes-de-su-detencion\/","title":{"rendered":"Tec de Monterrey invit\u00f3 al presunto tirador de la Atlixc\u00e1yotl a su consejo consultivo antes de su detenci\u00f3n"},"content":{"rendered":"<p>El Tecnol\u00f3gico de Monterrey Campus Puebla extendi\u00f3 una invitaci\u00f3n a Rafael N., se\u00f1alado por la Fiscal\u00eda General del Estado como presunto responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl, para integrarse al Consejo de la Escuela de Ingenier\u00eda y Ciencias. Este reconocimiento, fechado el 18 de junio de 2026, destacaba su \u201ctrayectoria, liderazgo y contribuci\u00f3n en el sector\u201d, aunque semanas despu\u00e9s de su captura, ocurrida la madrugada del martes 14 de julio de 2026 en el residencial Santa Fe de San Andr\u00e9s Cholula, el documento fue retirado de las plataformas institucionales.  <\/p>\n<p>Firmada por la directora general del campus, Viviana Ortiz Meill\u00f3n, y el director de la Escuela de Ingenier\u00eda y Ciencias, Jorge Antonil Reyes Avenda\u00f1o, la invitaci\u00f3n buscaba incorporar a Rafael N. en un \u00f3rgano consultivo que fortalece la vinculaci\u00f3n entre la academia y el sector productivo. El Tecnol\u00f3gico justific\u00f3 la invitaci\u00f3n se\u00f1alando que su experiencia empresarial pod\u00eda aportar al desarrollo acad\u00e9mico y a la formaci\u00f3n estudiantil.  <\/p>\n<p>\u201cEsta invitaci\u00f3n responde al reconocimiento de su destacada trayectoria, liderazgo y contribuci\u00f3n en el sector, as\u00ed como a la valiosa perspectiva que, desde su experiencia, puede aportar al fortalecimiento de nuestros programas acad\u00e9micos y a la formaci\u00f3n de nuestros estudiantes\u201d, se lee en el oficio. Adem\u00e1s, se consideraba que su participaci\u00f3n ser\u00eda \u201cclave\u201d para definir objetivos y metas en el siguiente ciclo de trabajo de la Escuela de Ingenier\u00eda y Ciencias.  <\/p>\n<p>La revelaci\u00f3n de este documento se da un d\u00eda despu\u00e9s de que la Universidad Polit\u00e9cnica Metropolitana de Puebla intentara deslindarse del empresario, eliminando de sus redes sociales publicaciones en las que aparec\u00eda junto al rector Raymundo Atanacio Luna durante la firma de un convenio de colaboraci\u00f3n, y anunciando que analizaba rescindir dicho acuerdo.  <\/p>\n<p>Hasta el momento, el Tecnol\u00f3gico de Monterrey Campus Puebla no ha emitido un posicionamiento p\u00fablico para aclarar si Rafael N. lleg\u00f3 a incorporarse formalmente al consejo consultivo o si la invitaci\u00f3n qued\u00f3 sin efecto tras su detenci\u00f3n.  <\/p>\n<p>La Fiscal\u00eda General del Estado confirm\u00f3 que, adem\u00e1s de los delitos relacionados con los ataques en la V\u00eda Atlixc\u00e1yotl, Rafael N. enfrentar\u00e1 una imputaci\u00f3n por tentativa de homicidio, luego de que presuntamente disparara contra agentes ministeriales y elementos federales durante el operativo de captura.  <\/p>\n<p>Este caso pone en evidencia la compleja relaci\u00f3n entre instituciones educativas privadas y actores empresariales, y plantea cuestionamientos sobre los criterios para establecer v\u00ednculos que, en ocasiones, pueden legitimar figuras cuestionadas por la justicia. En un contexto donde la justicia social y la transparencia son urgentes, resulta indispensable que las universidades asuman un compromiso \u00e9tico con la sociedad y eviten alianzas que puedan socavar su credibilidad y responsabilidad social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tecnol\u00f3gico de Monterrey Campus Puebla extendi\u00f3 una invitaci\u00f3n a Rafael N., se\u00f1alado por la Fiscal\u00eda General del Estado como presunto responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl, para integrarse al Consejo de la Escuela de Ingenier\u00eda y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-100659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100659"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100659\/revisions"}],"predecessor-version":[{"id":100660,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100659\/revisions\/100660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100658"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}