{"id":100605,"date":"2026-07-15T10:48:25","date_gmt":"2026-07-15T10:48:25","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-rurales-por-extranjeros\/"},"modified":"2026-07-15T16:48:28","modified_gmt":"2026-07-15T16:48:28","slug":"argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-rurales-por-extranjeros","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/argentina-impulsa-ley-para-eliminar-limites-a-la-compra-de-tierras-rurales-por-extranjeros\/","title":{"rendered":"Argentina impulsa ley para eliminar l\u00edmites a la compra de tierras rurales por extranjeros"},"content":{"rendered":"<p>El gobierno argentino presentar\u00e1 en el Senado un proyecto para modificar la Ley 26.737 de Tierras Rurales, con la intenci\u00f3n de eliminar las restricciones que actualmente limitan la adquisici\u00f3n de campos por parte de extranjeros. Esta iniciativa forma parte de un paquete legislativo orientado a reforzar la inviolabilidad de la propiedad privada y a abrir el mercado rural a inversores internacionales, en un contexto donde la normativa vigente impide que los extranjeros superen el 15 por ciento del total de tierras rurales a nivel nacional, provincial y municipal.<\/p>\n<p>El vocero presidencial, Adri\u00e1n Ravier, defendi\u00f3 la propuesta argumentando que la legislaci\u00f3n actual \u201ccriminaliz\u00f3 de facto la compra de tierras por parte de extranjeros\u201d, lo que, seg\u00fan \u00e9l, contradice el esp\u00edritu constitucional que reconoce derechos civiles tanto a nacionales como a extranjeros. Ravier se\u00f1al\u00f3 que estas restricciones han frenado inversiones significativas, particularmente en sectores foresto-industriales de regiones como el NEA, Cuyo y la Patagonia, donde existen \u201cproyectos millonarios que no pueden desarrollarse por estas trabas\u201d.<\/p>\n<p>El proyecto distinguir\u00e1 entre inversores privados y Estados extranjeros. En este sentido, Ravier explic\u00f3 que gobiernos, empresas estatales o sociedades controladas por ellos deber\u00e1n enfrentar mayores exigencias: mientras que actualmente pueden comprar hasta mil hect\u00e1reas sin autorizaci\u00f3n, con la nueva ley requerir\u00e1n un permiso espec\u00edfico.<\/p>\n<p>Desde el sector inmobiliario rural, el debate tambi\u00e9n se centra en el impacto econ\u00f3mico. Lucas Palma, presidente de la C\u00e1mara Inmobiliaria Rural, afirm\u00f3 que para elevar el valor de los campos se requieren medidas m\u00e1s amplias, como la eliminaci\u00f3n de retenciones y reglas claras para la inversi\u00f3n. Por su parte, Federico Nordheimer, titular de Nordheimer Campos y Estancias, consider\u00f3 que el temor a una compra masiva de tierras por extranjeros responde m\u00e1s a un imaginario hist\u00f3rico que a la realidad del mercado. \u201cEs un miedo comprensible, con ra\u00edces hist\u00f3ricas y culturales profundas, pero quienes trabajamos d\u00eda a d\u00eda en el mercado inmobiliario rural sabemos que la realidad del sector cuenta una historia bastante diferente\u201d, se\u00f1al\u00f3.<\/p>\n<p>Actualmente, Argentina cuenta con cerca de 266.7 millones de hect\u00e1reas rurales, de las cuales 16.2 millones est\u00e1n en manos extranjeras, equivalente al 6 por ciento del total. La propuesta legislativa podr\u00eda abrir un nuevo cap\u00edtulo en la discusi\u00f3n sobre inversi\u00f3n, soberan\u00eda, producci\u00f3n agr\u00edcola y control territorial, temas que hist\u00f3ricamente han generado tensiones en un pa\u00eds marcado por la concentraci\u00f3n de la tierra y la desigualdad en el acceso a recursos productivos.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/catrina_nortena\/status\/2077146920322060355\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno argentino presentar\u00e1 en el Senado un proyecto para modificar la Ley 26.737 de Tierras Rurales, con la intenci\u00f3n de eliminar las restricciones que actualmente limitan la adquisici\u00f3n de campos por parte de extranjeros. Esta iniciativa forma parte de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-100605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100605"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100605\/revisions"}],"predecessor-version":[{"id":100606,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100605\/revisions\/100606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100604"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}