{"id":100593,"date":"2026-07-15T10:24:07","date_gmt":"2026-07-15T10:24:07","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/murio-elsa-aguirre-actriz-emblematica-del-cine-de-oro-mexicano\/"},"modified":"2026-07-15T16:24:08","modified_gmt":"2026-07-15T16:24:08","slug":"murio-elsa-aguirre-actriz-emblematica-del-cine-de-oro-mexicano","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/15\/murio-elsa-aguirre-actriz-emblematica-del-cine-de-oro-mexicano\/","title":{"rendered":"Muri\u00f3 Elsa Aguirre, actriz emblem\u00e1tica del Cine de Oro mexicano"},"content":{"rendered":"<p>El cine mexicano perdi\u00f3 a una de sus figuras m\u00e1s representativas de la \u00c9poca de Oro. Elsa Aguirre, reconocida actriz y s\u00edmbolo de ese periodo, falleci\u00f3 la noche del martes 14 de julio de 2026, a los 85 a\u00f1os de edad.  <\/p>\n<p>La noticia fue confirmada durante la madrugada del mi\u00e9rcoles 15 de julio a trav\u00e9s del perfil oficial de Facebook de la actriz, donde se inform\u00f3 que muri\u00f3 \u201crodeada de amor y atenci\u00f3n en su casa de Cuernavaca, Morelos\u201d. En el mismo comunicado se destac\u00f3 que Aguirre se mostr\u00f3 complacida por los mensajes de cari\u00f1o que recibi\u00f3 y disfrut\u00f3 compartir sus experiencias mediante videos con sus seguidores.  <\/p>\n<p>La Asociaci\u00f3n Nacional de Int\u00e9rpretes (ANDI) lament\u00f3 profundamente su fallecimiento y resalt\u00f3 que Elsa Aguirre fue \u201cuna de las actrices m\u00e1s ic\u00f3nicas y emblem\u00e1ticas de la \u00c9poca de Oro del cine mexicano, c\u00e9lebre tanto por su talento dram\u00e1tico como por ser considerada uno de los rostros m\u00e1s bellos de la pantalla grande\u201d.  <\/p>\n<p>Elsa Irma Aguirre Ju\u00e1rez naci\u00f3 el 25 de septiembre de 1930 en Chihuahua, hija del general Jes\u00fas Aguirre y Emma Ju\u00e1rez. Su ingreso al cine fue fortuito: a los 14 a\u00f1os gan\u00f3 un concurso de belleza convocado por la productora CLASA Films Mundiales, lo que la llev\u00f3 a debutar en la comedia de ciencia ficci\u00f3n El sexo fuerte (1945), junto a su hermana Alma Rosa Aguirre.  <\/p>\n<p>Su carrera se consolid\u00f3 r\u00e1pidamente, con su primer papel estelar en Don Sim\u00f3n de Lira (1946), bajo la direcci\u00f3n de Julio Bracho y compartiendo cr\u00e9ditos con Joaqu\u00edn Pardav\u00e9. A lo largo de m\u00e1s de cinco d\u00e9cadas particip\u00f3 en m\u00e1s de 50 pel\u00edculas, abarcando g\u00e9neros que iban desde el drama hasta la comedia. Entre sus trabajos m\u00e1s destacados se encuentran La mujer que yo am\u00e9 (1950), Cuidado con el amor (1954) \u2014junto a Pedro Infante\u2014, Lluvia roja (1950) con Jorge Negrete y Algo flota sobre el agua (1948), coprotagonizada por Arturo de C\u00f3rdova.  <\/p>\n<p>En reconocimiento a su trayectoria, la Academia Mexicana de Artes y Ciencias Cinematogr\u00e1ficas (AMACC) le otorg\u00f3 en 2003 el Premio Ariel Honor\u00edfico, un reconocimiento a su contribuci\u00f3n fundamental al cine nacional.  <\/p>\n<p>La partida de Elsa Aguirre representa no solo la p\u00e9rdida de una artista, sino tambi\u00e9n el cierre de un cap\u00edtulo esencial en la historia cultural de M\u00e9xico, marcado por un cine que, pese a las transformaciones sociales y econ\u00f3micas, sigue siendo referente de identidad y memoria colectiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cine mexicano perdi\u00f3 a una de sus figuras m\u00e1s representativas de la \u00c9poca de Oro. Elsa Aguirre, reconocida actriz y s\u00edmbolo de ese periodo, falleci\u00f3 la noche del martes 14 de julio de 2026, a los 85 a\u00f1os de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-100593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100593"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100593\/revisions"}],"predecessor-version":[{"id":100594,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100593\/revisions\/100594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100592"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}