{"id":100452,"date":"2026-07-14T10:31:07","date_gmt":"2026-07-14T10:31:07","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/14\/convenio-con-presunto-implicado-en-caso-del-tirador-de-la-atlixcayotl-reaviva-debate-sobre-protocolos-institucionales\/"},"modified":"2026-07-14T16:31:21","modified_gmt":"2026-07-14T16:31:21","slug":"convenio-con-presunto-implicado-en-caso-del-tirador-de-la-atlixcayotl-reaviva-debate-sobre-protocolos-institucionales","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/14\/convenio-con-presunto-implicado-en-caso-del-tirador-de-la-atlixcayotl-reaviva-debate-sobre-protocolos-institucionales\/","title":{"rendered":"Convenio con presunto implicado en caso del \u201ctirador de la Atlixc\u00e1yotl\u201d reaviva debate sobre protocolos institucionales"},"content":{"rendered":"<p>El pasado 20 de abril, el rector de la Universidad Polit\u00e9cnica Metropolitana de Puebla (UPMP), Raymundo Atanacio Luna, exdiputado federal de Morena, firm\u00f3 un convenio de colaboraci\u00f3n con la asociaci\u00f3n civil ITEBIO A.C., representada por Rafael Zabalza, con el prop\u00f3sito de impulsar proyectos acad\u00e9micos, cient\u00edficos, tecnol\u00f3gicos y culturales.  <\/p>\n<p>Este acuerdo fue difundido por la propia universidad como una estrategia para fortalecer la vinculaci\u00f3n institucional mediante actividades de investigaci\u00f3n, capacitaci\u00f3n y desarrollo. Sin embargo, la relevancia del convenio ha resurgido tras la detenci\u00f3n de Rafael Z., se\u00f1alado por las autoridades como el presunto responsable de los ataques armados contra automovilistas en la V\u00eda Atlixc\u00e1yotl.  <\/p>\n<p>Hasta el momento, la Fiscal\u00eda no ha confirmado si el representante de ITEBIO A.C. y el detenido son la misma persona, aunque diversos reportes period\u00edsticos los vinculan. Adem\u00e1s, medios locales han documentado que Rafael Z. fue durante a\u00f1os un proveedor importante de medicamentos y equipo m\u00e9dico para el Gobierno de Puebla en las administraciones de Melquiades Morales y Mario Mar\u00edn, un dato que a\u00f1ade complejidad al contexto del caso.  <\/p>\n<p>Es importante destacar que al momento de la firma del convenio no exist\u00eda una investigaci\u00f3n p\u00fablica en contra de Rafael Z., pero el caso ha puesto en evidencia la necesidad de revisar los mecanismos con los que cuentan las instituciones p\u00fablicas para evaluar la vigencia de sus convenios cuando alguno de sus firmantes enfrenta investigaciones por delitos de alto impacto.  <\/p>\n<p>Hasta hoy, la Universidad Polit\u00e9cnica Metropolitana de Puebla no ha emitido un posicionamiento oficial sobre el convenio ni ha informado si \u00e9ste permanecer\u00e1 vigente o ser\u00e1 objeto de revisi\u00f3n ante los acontecimientos recientes.  <\/p>\n<p>Este episodio abre una discusi\u00f3n necesaria sobre la conveniencia de establecer protocolos claros para evaluar la continuidad o suspensi\u00f3n de convenios institucionales, con el fin de preservar la confianza p\u00fablica y el prestigio de las instituciones, sin perder de vista el respeto al debido proceso y la presunci\u00f3n de inocencia.  <\/p>\n<p>En un contexto donde la transparencia y la responsabilidad social deben ser pilares fundamentales de las instituciones p\u00fablicas, resulta indispensable que se fortalezcan los controles y se garantice que la colaboraci\u00f3n acad\u00e9mica y cultural no se vea comprometida por v\u00ednculos cuestionables, especialmente en un estado como Puebla, donde la justicia social y la rendici\u00f3n de cuentas siguen siendo demandas urgentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 20 de abril, el rector de la Universidad Polit\u00e9cnica Metropolitana de Puebla (UPMP), Raymundo Atanacio Luna, exdiputado federal de Morena, firm\u00f3 un convenio de colaboraci\u00f3n con la asociaci\u00f3n civil ITEBIO A.C., representada por Rafael Zabalza, con el prop\u00f3sito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-100452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100452"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100452\/revisions"}],"predecessor-version":[{"id":100453,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100452\/revisions\/100453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100451"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}