{"id":100449,"date":"2026-07-14T10:26:55","date_gmt":"2026-07-14T10:26:55","guid":{"rendered":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/14\/catean-presuntas-oficinas-del-tirador-de-la-atlixcayotl-en-la-colonia-el-vergel\/"},"modified":"2026-07-14T16:26:57","modified_gmt":"2026-07-14T16:26:57","slug":"catean-presuntas-oficinas-del-tirador-de-la-atlixcayotl-en-la-colonia-el-vergel","status":"publish","type":"post","link":"https:\/\/resistenciamex.com\/index.php\/2026\/07\/14\/catean-presuntas-oficinas-del-tirador-de-la-atlixcayotl-en-la-colonia-el-vergel\/","title":{"rendered":"Catean presuntas oficinas del \u201ctirador de la Atlixc\u00e1yotl\u201d en la colonia El Vergel"},"content":{"rendered":"<p>Este martes 14 de julio de 2026, elementos de la Fiscal\u00eda General del Estado (FGE), en coordinaci\u00f3n con la Polic\u00eda Estatal, realizan un cateo en un inmueble ubicado en la 27 Poniente, entre las calles 29 y 31 Poniente, en la colonia El Vergel, Puebla.  <\/p>\n<p>La diligencia se desarrolla horas despu\u00e9s de la detenci\u00f3n del empresario Rafael Z., ocurrida durante la madrugada en el fraccionamiento Santa Fe, se\u00f1alado como el presunto responsable de una serie de ataques con arma de fuego contra automovilistas en la V\u00eda Atlixc\u00e1yotl. Aunque de manera preliminar se ha informado que el inmueble cateado corresponder\u00eda a sus oficinas, la Fiscal\u00eda no ha confirmado oficialmente esta informaci\u00f3n.  <\/p>\n<p>El caso del denominado \u201ctirador de la Atlixc\u00e1yotl\u201d ha generado preocupaci\u00f3n social debido a que la Fiscal\u00eda documenta al menos 10 ataques con disparos, adem\u00e1s de una decena de hechos en investigaci\u00f3n, ocurridos principalmente entre enero y junio de este a\u00f1o. Los agresores atacaron a automovilistas y motociclistas que transitaban por la zona de Angel\u00f3polis, una de las \u00e1reas m\u00e1s transitadas y emblem\u00e1ticas de Puebla.  <\/p>\n<p>Este tipo de violencia refleja la persistente inseguridad que afecta a la poblaci\u00f3n y la necesidad de fortalecer las estrategias de prevenci\u00f3n y justicia. En este contexto, la coordinaci\u00f3n entre las autoridades estatales y locales resulta fundamental para garantizar la seguridad colectiva y el derecho a la movilidad segura.  <\/p>\n<p>Se espera que en las pr\u00f3ximas horas la Fiscal\u00eda General del Estado informe oficialmente los resultados del cateo y precise si el inmueble est\u00e1 vinculado directamente con la investigaci\u00f3n o con el detenido. Este avance en la investigaci\u00f3n es un paso necesario para esclarecer los hechos y ofrecer respuestas a una ciudadan\u00eda que demanda justicia y seguridad.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/PrimeraPPuebla\/status\/2077033135909249046\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 14 de julio de 2026, elementos de la Fiscal\u00eda General del Estado (FGE), en coordinaci\u00f3n con la Polic\u00eda Estatal, realizan un cateo en un inmueble ubicado en la 27 Poniente, entre las calles 29 y 31 Poniente, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-100449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/comments?post=100449"}],"version-history":[{"count":1,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100449\/revisions"}],"predecessor-version":[{"id":100450,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/posts\/100449\/revisions\/100450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media\/100448"}],"wp:attachment":[{"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/media?parent=100449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/categories?post=100449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resistenciamex.com\/index.php\/wp-json\/wp\/v2\/tags?post=100449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}